{"id":150,"date":"2015-12-16T05:35:51","date_gmt":"2015-12-16T05:35:51","guid":{"rendered":"http:\/\/themes.elmastudio.de\/neubau\/?p=150"},"modified":"2018-07-05T09:26:42","modified_gmt":"2018-07-05T07:26:42","slug":"kulturwissenschaftliche_aesthetik","status":"publish","type":"post","link":"https:\/\/www.aesthetik.hu-berlin.de\/de\/kulturwissenschaftliche_aesthetik\/","title":{"rendered":"\u00c4sthetiken der Grauzonen und Ambiguit\u00e4ten"},"content":{"rendered":"<p>Wissenschaftliche Labore, Flie\u00dfb\u00e4nder, Archive, K\u00fcchen, Flugzeuge, Lager und Hospize besitzen ihre eigene \u00c4sthetik. Das gilt f\u00fcr Geldscheine, Krankheiten, Uniformen, Stammb\u00e4ume, Staats- und Wappentiere und Waffen im Krieg gleicherma\u00dfen. Darin verk\u00f6rpert sich jeweils eine bestimmte Macht und bringt ihre eigent\u00fcmliche Herrschaft und spezifische Gewalt zur Erscheinung: Kein politisches System, keine \u00f6konomische Organisation und epistemische Ordnung, keine h\u00e4usliche, sexuelle oder b\u00fcrokratische Institution kann es sich leisten, \u00e4sthetisch abstinent zu sein. Um wirksam zu sein und ihre eigent\u00fcmliche Kraft und Gewalt zu entfalten, sind sie jeweils in konstitutiver Weise auf sinnliche Ordnungen, Inszenierungen, Visualisierungen, Fiktionen, Gr\u00fcndungsmythen, Phantasmen, Narrative und Symbole, auf Beobachtungs-, Registrierungs- und Identifizierungsma\u00dfnahmen angewiesen. Welche Rolle, so fragen wir, spielen \u00e4sthetische Verfahren, Wahrnehmungsweisen und Darstellungsformen f\u00fcr die Konstitution des Politischen im Widerstreit mit der Politik?<\/p>\n<p>\u00bbWo Macht ist, ist auch Widerstand.\u00ab Wo es Gewalt gibt, die \u00bbzwingt, beugt, bricht, zerst\u00f6rt\u00ab, da gibt es Gegengewalt. Nietzsches und Foucaults Einsicht in relationale und machtdiagnostische Dynamiken hat auch und gerade Konsequenzen f\u00fcr \u00c4sthetiken des Widerstands, f\u00fcr Erfahrungen des Leids, des Verloren-, Bedeutungslos-, Unsichtbar-, Zur\u00fcckgelassen-, Abgekoppeltseins einerseits und f\u00fcr die erstaunlichen M\u00f6glichkeiten andererseits, die sich in Situationen von Passivit\u00e4t und Ohnmacht f\u00fcr neue Sensibilit\u00e4ten und Resonanzr\u00e4ume, f\u00fcr Umwertungen, Transformationen, fintenreiche Neucodierungen und Stile, listige Enteignungs-, Konsum- und Gebrauchsweisen, subversive Praktiken, Irritationen, Ordnungsst\u00f6rungen, Lebensformen und revolution\u00e4re Bewegungen nicht zuletzt im \u00e4sthetischen Sinne ergeben.<\/p>\n<p>Doch Befehlsmacht und Verweigerung, Gewalt und Widerstand, Fremd- und Selbstbestimmung sind vielfach keine Handlungs- und Leidenssph\u00e4ren, die sich wie Wei\u00df und Schwarz, Land und Meer gegen\u00fcberstehen und klar und deutlich voneinander unterschieden w\u00e4ren. Sie entfalten ihre signifikanten Kr\u00e4fte und Wirkungen vielmehr in vertrackten Beziehungsnetzen, nicht selten in extremer N\u00e4he und in polymorphen Machtrelationen. Unsere kulturhistorische und kulturtheoretische Aufmerksamkeit gilt daher vor allem den \u00c4sthetiken der Grauzonen und Ambiguit\u00e4ten.<\/p>","protected":false},"excerpt":{"rendered":"<p>Wissenschaftliche Labore, Flie\u00dfb\u00e4nder, Archive, K\u00fcchen, Flugzeuge, Lager und Hospize besitzen ihre eigene \u00c4sthetik. Das gilt f\u00fcr Geldscheine, Krankheiten, Uniformen, Stammb\u00e4ume, Staats- und Wappentiere und Waffen im Krieg gleicherma\u00dfen. Darin verk\u00f6rpert sich jeweils eine bestimmte Macht und bringt ihre eigent\u00fcmliche Herrschaft und spezifische Gewalt zur Erscheinung:&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1748,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.aesthetik.hu-berlin.de\/de\/wp-json\/wp\/v2\/posts\/150"}],"collection":[{"href":"https:\/\/www.aesthetik.hu-berlin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aesthetik.hu-berlin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aesthetik.hu-berlin.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aesthetik.hu-berlin.de\/de\/wp-json\/wp\/v2\/comments?post=150"}],"version-history":[{"count":22,"href":"https:\/\/www.aesthetik.hu-berlin.de\/de\/wp-json\/wp\/v2\/posts\/150\/revisions"}],"predecessor-version":[{"id":904,"href":"https:\/\/www.aesthetik.hu-berlin.de\/de\/wp-json\/wp\/v2\/posts\/150\/revisions\/904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aesthetik.hu-berlin.de\/de\/wp-json\/wp\/v2\/media\/1748"}],"wp:attachment":[{"href":"https:\/\/www.aesthetik.hu-berlin.de\/de\/wp-json\/wp\/v2\/media?parent=150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aesthetik.hu-berlin.de\/de\/wp-json\/wp\/v2\/categories?post=150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aesthetik.hu-berlin.de\/de\/wp-json\/wp\/v2\/tags?post=150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}